{"id":5512,"date":"2022-12-09T12:45:32","date_gmt":"2022-12-09T12:45:32","guid":{"rendered":"https:\/\/freewalkingtoursbordeaux.com\/?page_id=5512"},"modified":"2024-05-16T10:55:42","modified_gmt":"2024-05-16T10:55:42","slug":"free-tour-saint-emilion","status":"publish","type":"page","link":"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/","title":{"rendered":"Free Tour Saint Emilion"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5512\" class=\"elementor elementor-5512\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1761a59 elementor-section-full_width elementor-section-height-default elementor-section-height-default row-top\" data-id=\"1761a59\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e33d954\" data-id=\"e33d954\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81bd05a elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"81bd05a\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/01\/turno-vino-saint-emilion-600x600.jpg\" alt=\"turno-vino-saint-emilion\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/03\/saint-emilion-wine-tour-photo-2-600x590.jpg\" alt=\"Saint Emilion Tour\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/03\/saint-emilion-wine-tour-photo-1-600x590.jpg\" alt=\"saint-emilion-wine-tour-photo-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/01\/Torre-campana-iglesia-monolitica-saint-emilion-600x600.jpg\" alt=\"Torre-campana-iglesia-monolitica-saint-e,milion\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/03\/saint-emilion-wine-tour-photo-4-600x590.jpg\" alt=\"Saint Emilion Wine route\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/01\/iglesia-monolitica-600x600.jpg\" alt=\"iglesia-monolitica\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/02\/Vineyards-Bordeaux-France-600x600.jpg\" alt=\"Vineyards-Bordeaux-France\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/01\/claustro-iglesia-saint-emilion-600x600.jpg\" alt=\"claustro-iglesia-saint-emilion\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/03\/saint-emilion-wine-tour-photo-3-600x590.jpg\" alt=\"saint-emilion-wine-tour-photo-3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3718046 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"3718046\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8957f96\" data-id=\"8957f96\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6ff897 elementor-widget elementor-widget-heading\" data-id=\"e6ff897\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Free tour Saint Emilion en espa\u00f1ol<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5c63bee elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"5c63bee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-af79721\" data-id=\"af79721\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-446fe80 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"446fe80\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\" las la-map-signs\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rue Guadet 1 Saint-\u00c9milion 33330 Nouvelle-Aquitaine FR<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b824589\" data-id=\"b824589\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-385a8f1 elementor-widget elementor-widget-button\" data-id=\"385a8f1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#book\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AHORA<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3221ceb\" data-id=\"3221ceb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5287a84 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"5287a84\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-euro-sign\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tPrecio\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBasado en propinas\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-52ab491\" data-id=\"52ab491\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ed10f7 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"8ed10f7\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tDuracion\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t1.5 horas\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-60c9472\" data-id=\"60c9472\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4449a60 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"4449a60\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-walking\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tTipo de tour\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTour de grupo\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ef3530 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"3ef3530\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e527308\" data-id=\"e527308\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f10a2d elementor-widget elementor-widget-menu-anchor\" data-id=\"9f10a2d\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\nbody.elementor-page .elementor-widget-menu-anchor{margin-bottom:0}<\/style>\t\t<div id=\"book\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d4bd20 elementor-widget elementor-widget-heading\" data-id=\"2d4bd20\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lamentablemente no hay Saint Emilion Tours hasta nuevo aviso. Lamentamos las molestias<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43fb43f elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"43fb43f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6fddc34\" data-id=\"6fddc34\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a498f3 elementor-widget elementor-widget-text-editor\" data-id=\"2a498f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h2>DESCRIPCI\u00d3N<\/h2><p><strong>Descubra el pintoresco pueblo medieval de Saint Emilion en esta nueva visita gratuita. \u00bfHa dicho VINO? Saint Emilion tiene taaaanto m\u00e1s que ofrecer: un ermita\u00f1o que cambi\u00f3 el pan por madera, el origen del famoso macaron, el monolito m\u00e1s grande y muchas m\u00e1s historias interesantes.<\/strong><\/p><p>Acomp\u00e1\u00f1enos a explorar uno de los pueblos m\u00e1s bonitos de Francia, Saint Emilion, en nuestro recorrido a pie gratuito. Saint Emilion es mundialmente famoso por su vino y sus vi\u00f1edos, pero el pueblo en s\u00ed tambi\u00e9n tiene mucho que ver y descubrir.<\/p><p>Visitaremos los lugares m\u00e1s importantes y algunas joyas ocultas en este Tour Gratis de Saint Emilion, que es Patrimonio de la Humanidad por la UNESCO desde 1999 y los primeros vi\u00f1edos del mundo en lograr esta designaci\u00f3n.<\/p><p>Pasearemos y hablaremos del Pasado, Presente y Futuro de Saint Emilion:<\/p><ul><li>\u00bfSab\u00edas que el primer ciudadano de Saint Emilion fue Ausonius, ahora uno de los m\u00e1s prestigiosos ch\u00e2teau de vino conocido como Ch\u00e2teau Ausone,<\/li><li>Escuche la historia milagrosa del ermita\u00f1o Emilion que dio nombre al pueblo en el siglo VIII,<\/li><li>Conozca la historia de la iglesia monol\u00edtica m\u00e1s grande de Europa,<\/li><li>Camine por las calles empedradas de Saint Emilion mientras comprende los 100 a\u00f1os de guerra entre Francia e Inglaterra,<\/li><li>Escuche las historias de los prestigiosos propietarios de los castillos que se rebelaron durante la Revoluci\u00f3n Francesa,<\/li><li>Descubra la historia gastron\u00f3mica y vin\u00edcola local y tradicional de Saint Emilion con las recomendaciones de los mejores restaurantes de Saint Emilion<\/li><\/ul><p>\u00a1Y mucho m\u00e1s!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ffdadb elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"5ffdadb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-142df22\" data-id=\"142df22\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9442d3 elementor-widget elementor-widget-heading\" data-id=\"c9442d3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Descubre nuestros otros tours por Burdeos<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c6a11a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8c6a11a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-burdeos\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Free Tour por Burdeos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-cata-de-vino-burdeos\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tour por Burdeos degustaci\u00f3n de vinos y quesos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-gastronomico-burdeos\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tour gastron\u00f3mico en Burdeos - estilo Ap\u00e9ro franc\u00e9s<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-privado-por-burdeos\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tour privado visita a pie por Burdeos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-privado-del-vino-por-burdeos\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cata de vinos de Burdeos en grupo<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68795ce elementor-section-full_width elementor-section-height-default elementor-section-height-default row-top\" data-id=\"68795ce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f4bea52\" data-id=\"f4bea52\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7a5407 elementor-widget elementor-widget-gva-heading-block\" data-id=\"a7a5407\" data-element_type=\"widget\" data-widget_type=\"gva-heading-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"gva-element-gva-heading-block gva-element\">   <div class=\"align-center style-1 widget gsc-heading box-align-left auto-responsive\">\r\n      <div class=\"content-inner\">\r\n         \r\n                  \r\n                     <div class=\"sub-title\"><span>Experiencias similares<\/span><\/div>\r\n           \r\n         \r\n                     <h2 class=\"title\">\r\n               <span>Otros tours<\/span>\r\n            <\/h2>\r\n                  \r\n         \r\n      <\/div>\r\n   <\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a55e37e elementor-widget elementor-widget-global elementor-global-9785 elementor-widget-gva-services-group\" data-id=\"a55e37e\" data-element_type=\"widget\" data-widget_type=\"gva-services-group.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"gva-element-gva-services-group gva-element\">\r\n<div class=\"swiper-slider-wrapper gsc-services-group layout-carousel no-gutter style-1 \">\r\n   <div class=\"swiper-content-inner\">   \r\n      <div class=\"init-carousel-swiper swiper\" data-carousel=\"{&quot;items&quot;:4,&quot;items_lg&quot;:4,&quot;items_md&quot;:3,&quot;items_sm&quot;:2,&quot;items_xs&quot;:1,&quot;items_xx&quot;:1,&quot;effect&quot;:&quot;slide&quot;,&quot;space_between&quot;:30,&quot;loop&quot;:1,&quot;speed&quot;:600,&quot;autoplay&quot;:0,&quot;autoplay_delay&quot;:4500,&quot;autoplay_hover&quot;:1,&quot;navigation&quot;:1,&quot;pagination&quot;:0,&quot;dynamic_bullets&quot;:0,&quot;pagination_type&quot;:&quot;bullets&quot;}\">\r\n         <div class=\"swiper-wrapper\">\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Free Tour por Burdeos<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/free-tour-burdeos-1.jpg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-burdeos\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-burdeos\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Grupo peque\u00f1o: Tour con cata de vinos y quesos por Burdeos<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/Chartrons-Wine-and-cheese-scaled-1.jpg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-cata-de-vino-burdeos\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-cata-de-vino-burdeos\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Free Tour del Burdeos moderno al medieval<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/FREE-WALKING-TOUR-BORDEAUX-MEDIEVAL-TO-MODERN-scaled-1.jpg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Free Tour por Saint Emilion<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/Saint-Emilion-Wine-tour-580x450-1.jpeg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Grupo peque\u00f1o: Tour gastron\u00f3mico de Burdeos<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/basilica-san-miguel-burdeos.jpg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-gastronomico-burdeos\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-gastronomico-burdeos\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Tour privado: Lo mejor de Burdeos<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/Bordeaux-wine-tour.jpeg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-privado-por-burdeos\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-privado-por-burdeos\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Tour privado: Lo mejor de Saint Emilion<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/Village-Saint-Emilion.jpg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-saint-emilion-vino\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-saint-emilion-vino\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Tour: lo mejor de Burdeos a pie + degustaci\u00f3n de vinos y quesos<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"http:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2024\/05\/Bordeaux-Letter.jpg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/cata-de-vino-y-quesos-en-burdeos\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/cata-de-vino-y-quesos-en-burdeos\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                     <\/div> \r\n      <\/div>\r\n   <\/div>   \r\n   <div class=\"swiper-pagination\"><\/div>   <div class=\"swiper-nav-next\"><\/div><div class=\"swiper-nav-prev\"><\/div><\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-343fc0f elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"343fc0f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dd4e3b2\" data-id=\"dd4e3b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d2d939 elementor-widget elementor-widget-heading\" data-id=\"6d2d939\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VIDEO DESCRIPCI\u00d3N DEL TOUR<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-264584c elementor-widget elementor-widget-video\" data-id=\"264584c\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=CBo1il1A9FE&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;right:0;bottom:0;left:0;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%;aspect-ratio:var(--video-aspect-ratio);-o-object-fit:cover;object-fit:cover;-o-object-position:center center;object-position:center center}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-custom-embed-image-overlay{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-custom-embed-image-overlay img{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f298262\" data-id=\"f298262\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6778efa elementor-widget elementor-widget-text-editor\" data-id=\"6778efa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u00bfC\u00f3mo llegar a Saint Emilion desde Burdeos?<\/strong><\/p><p><strong>Llegada en tren:<\/strong> El trayecto en tren desde la estaci\u00f3n de St Jean en Burdeos hasta la estaci\u00f3n de St Emilion es de 35 min a 55 min. Llegue al menos 20 minutos antes de que empiece la visita, ya que se tarda 15 minutos andando en llegar al punto de partida desde la estaci\u00f3n.<\/p><p><span data-offset-key=\"1vl2k-0-0\"><strong>En autob\u00fas:<\/strong> TransGironde funciona regularmente en verano, Bus Nr 302 comienza en Place Quinconces en el centro de la ciudad de Burdeos.<\/span><\/p><p><strong>En coche:<\/strong> <span data-offset-key=\"hqh2-0-0\">40min de camino desde Burdeos. <\/span>Llegue pronto para buscar aparcamiento, todos los aparcamientos de St Emilion y alrededores son de pago.<\/p><p>Mas informaci\u00f3n acerca del transporte <a href=\"https:\/\/www.saint-emilion-tourisme.com\/es\/infos-pratiques\/venir.html\">aqui.<\/a><\/p><p>Por favor, prevea suficiente tiempo para el viaje y el aparcamiento para llegar al punto de encuentro a tiempo para el inicio del tour. El gu\u00eda no puede esperar a los que llegan tarde.<\/p><p>Importante:<\/p><ul><li>Traer zapatos para caminar<\/li><li>Desafortunadamente el acceso de cochecitos y sillas de ruedas es limitado (escaleras, adoquines)<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4626c0 elementor-widget elementor-widget-button\" data-id=\"b4626c0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#book\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR ESTE TOUR<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d02f31 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"1d02f31\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a46048\" data-id=\"4a46048\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0a31a7 elementor-widget elementor-widget-heading\" data-id=\"a0a31a7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">INCLUIDO\/ EXCLUIDO<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-df06c84 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"df06c84\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a3f19ef\" data-id=\"a3f19ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16e4915 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"16e4915\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gu\u00eda amable y experimentado<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Grandes y peque\u00f1os secretos de Saint Emilion<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nuestras recomendaciones para comer, beber y disfrutar de la ciudad<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Llueva o haga sol - \u00a1nuestro tour tiene lugar decida lo que decida el dios del tiempo!<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Un agradable paseo por el pueblo medieval de Saint Emilion<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Una experiencia \u00fanica basada en las propinas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Se admiten mascotas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f1419d1\" data-id=\"f1419d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f262bdb elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f262bdb\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Entrada a cualquier monumento (\u00a1Iglesia monol\u00edtica s\u00f3lo accesible a trav\u00e9s de un tour pagado por la oficina de turismo!)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vino o aperitivos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24829b bg-row-theme elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"24829b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-663a9f23\" data-id=\"663a9f23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c5ae133 elementor-widget elementor-widget-gva-heading-block\" data-id=\"6c5ae133\" data-element_type=\"widget\" data-widget_type=\"gva-heading-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"gva-element-gva-heading-block gva-element\">   <div class=\"align-left style-1 widget gsc-heading box-align-left auto-responsive\">\r\n      <div class=\"content-inner\">\r\n         \r\n                  \r\n                     <div class=\"sub-title\"><span>Plan your trip with us<\/span><\/div>\r\n           \r\n         \r\n                     <h2 class=\"title\">\r\n               <span>\u00bfPreparado para un tour inolvidable?<\/span>\r\n            <\/h2>\r\n                  \r\n         \r\n      <\/div>\r\n   <\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2f34f947\" data-id=\"2f34f947\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7029da7e elementor-align-right elementor-widget elementor-widget-button\" data-id=\"7029da7e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#book\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AHORA TU TOUR<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3110638 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"3110638\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40a99c7\" data-id=\"40a99c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f73c744 elementor-widget elementor-widget-heading\" data-id=\"f73c744\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TOUR ITINERARY<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02417d1 elementor-widget elementor-widget-accordion\" data-id=\"02417d1\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-accordion{text-align:left}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2361\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2361\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Punto de partida de nuestro Free Tour por Saint Emilion<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2361\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2361\"><p><small class=\"sc-loNoSo clohiV\">Rue Guadet 1, 33330 Saint-\u00c9milion<\/small><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2362\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2362\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Primer punto destacado de la visita: la Porte Cad\u00e8ne - la puerta que separaba la ciudad baja de la alta en el siglo XIII<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2362\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2362\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2363\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2363\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">El famoso Cordeliers Cloister del siglo XIV: el lugar donde se produce vino espumoso desde el siglo XIX<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2363\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2363\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2364\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2364\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Puerta de Brunet: restante puerta de entrada al medival Saint Emilion con hermosa vista sobre los vi\u00f1edos<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2364\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2364\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2365\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2365\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Iglesia monol\u00edtica y su campanario: Esto es lo m\u00e1s destacado de San Emilion - la iglesia subterr\u00e1nea m\u00e1s grande de Europa.<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2365\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2365\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2366\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2366\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">La torre del Rey - pero \u00bfa qu\u00e9 rey pertenec\u00eda?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2366\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2366\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2367\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2367\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Descubre la ciudad baja con sus peque\u00f1os pasajes, adoquines y vida de pueblo<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2367\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2367\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2368\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2368\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00a1Y mucho m\u00e1s que eso!<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2368\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2368\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-95ce55b elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"95ce55b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0b04b1e\" data-id=\"0b04b1e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc0aa89 elementor-widget elementor-widget-heading\" data-id=\"cc0aa89\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PUNTO DE ENCUENTRO:\n1 Rue Guadet, 33330 St Emilion; plaza junto al cajero autom\u00e1tico de Banque Populaire<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-994a707 elementor-widget elementor-widget-google_maps\" data-id=\"994a707\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-google_maps .elementor-widget-container{overflow:hidden}.elementor-widget-google_maps .elementor-custom-embed{line-height:0}.elementor-widget-google_maps iframe{height:300px}<\/style>\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=1%20Rue%20Guadet%2C%2033330%20Saint-%C3%89milion&#038;t=m&#038;z=17&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"1 Rue Guadet, 33330 Saint-\u00c9milion\"\n\t\t\t\t\taria-label=\"1 Rue Guadet, 33330 Saint-\u00c9milion\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f9ede0 elementor-widget elementor-widget-image\" data-id=\"2f9ede0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"707\" height=\"68\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/01\/IDENTIFICA-A-NUESTROS-GUI\u0301AS-CON-EL-PARAGUAS-TURQUESAAZUL..png\" class=\"attachment-large size-large wp-image-5775\" alt=\"Identifica a nuestros gu\u00edas con el paraguas azul turquesa\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73d712f elementor-widget elementor-widget-image-carousel\" data-id=\"73d712f\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay_speed&quot;:1000,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/12\/BEST-COMMENTS-1.png\" alt=\"Best Comments\" \/><figcaption class=\"elementor-image-carousel-caption\">MEJORES NOTAS<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/12\/recycle-umbrella.png\" alt=\"Umbrella Recycle\" \/><figcaption class=\"elementor-image-carousel-caption\">PARAGUAS ECO<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/12\/Recycleipads.png\" alt=\"Ipad Recycle\" \/><figcaption class=\"elementor-image-carousel-caption\">IPAD REUTILIZADOS<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62f9da7 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"62f9da7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb758b2\" data-id=\"bb758b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40c3bd3 elementor-widget elementor-widget-gva-heading-block\" data-id=\"40c3bd3\" data-element_type=\"widget\" data-widget_type=\"gva-heading-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"gva-element-gva-heading-block gva-element\">   <div class=\"align-center style-1 widget gsc-heading box-align-left auto-responsive\">\r\n      <div class=\"content-inner\">\r\n         \r\n                  \r\n                     <div class=\"sub-title\"><span>Testimonios y comentarios<\/span><\/div>\r\n           \r\n         \r\n                     <h2 class=\"title\">\r\n               <span>A ellos les encantaron nuestros tours<\/span>\r\n            <\/h2>\r\n                  \r\n         \r\n      <\/div>\r\n   <\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-707e347 elementor-widget elementor-widget-gva-testimonials\" data-id=\"707e347\" data-element_type=\"widget\" data-widget_type=\"gva-testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"gva-element-gva-testimonials gva-element\">\t<div class=\"gva-testimonial-carousel swiper-slider-wrapper style-2 \">\r\n\t\t<div class=\"swiper-content-inner\">\r\n\t\t\t<div class=\"init-carousel-swiper swiper\" data-carousel=\"{&quot;items&quot;:3,&quot;items_lg&quot;:3,&quot;items_md&quot;:3,&quot;items_sm&quot;:2,&quot;items_xs&quot;:1,&quot;items_xx&quot;:1,&quot;effect&quot;:&quot;slide&quot;,&quot;space_between&quot;:15,&quot;loop&quot;:1,&quot;speed&quot;:600,&quot;autoplay&quot;:1,&quot;autoplay_delay&quot;:4500,&quot;autoplay_hover&quot;:1,&quot;navigation&quot;:1,&quot;pagination&quot;:0,&quot;dynamic_bullets&quot;:0,&quot;pagination_type&quot;:&quot;bullets&quot;}\">\r\n\t\t\t\t<div class=\"swiper-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item swiper-slide\">\r\n\t\t\t\t\t\t\t<div class=\"testimonial-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-image\">\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/03\/free-walking-tour-photo-4-e1657135098591.jpg\" alt=\"Miriam\" \/>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-content\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-stars\">\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-quote\">\r\n\t\t\t\t\t\t\t\t\t\tTour y gu\u00eda (Leticia) maravillosos!\nEl tour fue muy interesante y entretenido, y las dos horas que dur\u00f3 se pasaron volando. Ella fue muy maja y cercana con todos, dio muy buenas recomendaciones y datos hist\u00f3ricos, fue una gran gu\u00eda.Lo recomendamos al 100%.\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-meta\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-name\">Miriam<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-job\">Espa\u00f1a - Tripadvisor<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item swiper-slide\">\r\n\t\t\t\t\t\t\t<div class=\"testimonial-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-image\">\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/04\/Free-tour-wit-Adrian-e1657134860244.jpeg\" alt=\"Alaitzp\" \/>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-content\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-stars\">\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-quote\">\r\n\t\t\t\t\t\t\t\t\t\tMuy buen Tour. Adri\u00e1n ha sido el mejor gu\u00eda!Te cuenta la historia y curiosidades interesantes de Burdeos de una forma entretenida. Adem\u00e1s te da muchas ideas para comer, vistas, salir, diferentes.\nSuper recomendable\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-meta\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-name\">Alaitzp<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-job\">Espa\u00f1a - Tripadvisor<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item swiper-slide\">\r\n\t\t\t\t\t\t\t<div class=\"testimonial-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-image\">\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/04\/Free-Walking-Tour-Bordeaux-2-e1657134909391.jpeg\" alt=\"Tatiana\" \/>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-content\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-stars\">\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-quote\">\r\n\t\t\t\t\t\t\t\t\t\tS\u00faper recomendado!\nExcelente ! Me gust\u00f3 mucho descubrir un poco de la ciudad de esta manera. Tips muy interesante de\nla ciudad y buenos consejos para comer y probar buenos vinos !\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-meta\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-name\">Tatiana<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-job\">Espa\u00f1a - Tripadvisor<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item swiper-slide\">\r\n\t\t\t\t\t\t\t<div class=\"testimonial-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-image\">\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2021-07-21-at-14.23.06-e1657135052831.jpeg\" alt=\"Maria\" \/>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-content\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-stars\">\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-quote\">\r\n\t\t\t\t\t\t\t\t\t\tVisita con amigas a Burdeos.\nLa gu\u00eda Melanie ha sido maravillosa! Sus explicaciones fant\u00e1sticas!! Y ella es encantadora! Hemos disfrutado mucho y aprendido bastante.\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-meta\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-name\">Maria<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-job\">Espa\u00f1a - Tripadvisor<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item swiper-slide\">\r\n\t\t\t\t\t\t\t<div class=\"testimonial-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-image\">\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/03\/free-walking-tour-bordeaux-image-1-e1657134980341.jpg\" alt=\"Marcher\" \/>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-content\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-stars\">\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-quote\">\r\n\t\t\t\t\t\t\t\t\t\tLuc\u00eda (La Gallega) ha sido una gu\u00eda magn\u00edfica! Super simp\u00e1tica, amable y atenta a cualquier pregunta o comentario que se le hiciera. Recomendable 100%!!!\n\nEl recorrido es muy bonito, lleno de historia y perfectamente \"aguantable\" en cuanto a cansancio.\n\nPerfecto para familias, amigos, parejas, etc.\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-meta\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-name\">Marcher<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-job\">Espa\u00f1a - Tripadvisor<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t\t\t<\/div>   \r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t\t      <div class=\"swiper-nav-next\"><\/div><div class=\"swiper-nav-prev\"><\/div>\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-535fe77 elementor-widget elementor-widget-shortcode\" data-id=\"535fe77\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"ti-widget ti-goog\" data-layout-id=\"5\" data-set-id=\"ligth-border\" data-pid=\"\" data-pager-autoplay-timeout=\"6\" data-review-target-width=\"275\" data-language=\"en\" > <div class=\"ti-widget-container ti-col-4\"> <div class=\"ti-footer source-Google\"> <div class=\"ti-rating-text\"> <strong class=\"ti-rating\"> Excellent <\/strong> <\/div> <span class=\"ti-stars star-lg\"> <span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span> <\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\">Based on <strong>540 reviews<\/strong><\/span> <\/div> <div class=\"ti-large-logo\"> <div class=\"ti-v-center\"> <img decoding=\"async\" class=\"ti-logo-fb\" src=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/logo.svg\" width=\"150\" height=\"25\" alt=\"Google\" \/> <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\"><\/div> <div class=\"ti-prev\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a-\/ACB-R5QjnJ0DdCXxCs9czqu-f9BFaiV73HahOH2vmDPjng=s120-c-c-rp-w64-h64-mo-br100\" alt=\"teresa arozena\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> teresa arozena <\/div> <div class=\"ti-date\">2023-04-28<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Muy buena experiencia, muy recomendable... todo el desarrollo hist\u00f3rico de Burdeos de una manera din\u00e1mica y ligera. Una buena forma de iniciaci\u00f3n en la ciudad con mucha informaci\u00f3n \u00fatil.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AGNmyxZsbiFZgxS7Pb4X71fI05SAHJPDXM7bld2o0wLF=s120-c-c-rp-w64-h64-mo-br100\" alt=\"Belen Garc\u00eda Balado\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Belen Garc\u00eda Balado <\/div> <div class=\"ti-date\">2023-04-28<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Luc\u00eda espectacular su explicaci\u00f3n y cercan\u00eda<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AGNmyxaryhpqPSQCYv6lsu0jjmYBMKzw77pSPVK3A4d9=s120-c-c-rp-w64-h64-mo-ba3-br100\" alt=\"Christine W\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Christine W <\/div> <div class=\"ti-date\">2023-04-27<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Lucia was our tour guide and she was amazing, extremely knowledgable and gave us an awesome tour. She gave us lots of recommendations for restaurants and other sites to see while in Bordeaux. Highly recommend this tour!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a-\/ACB-R5SFc8TmQKf6yZmyKTCJA7HN34YCJz0zDGSBh-OH=s120-c-c-rp-w64-h64-mo-ba3-br100\" alt=\"\u0414\u0430\u0440\u0438\u043d\u0430 \u0418\u0432\u0430\u043d\u0447\u0435\u043d\u043a\u043e\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> \u0414\u0430\u0440\u0438\u043d\u0430 \u0418\u0432\u0430\u043d\u0447\u0435\u043d\u043a\u043e <\/div> <div class=\"ti-date\">2023-04-27<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->The tour was really interesting, even back home I decided to read more about Ali\u00e9nor d'Aquitaine. Thank you!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AGNmyxY-naQKfVKjLZvBhIcAtCHJ7BMbkVShGV3tg8-h=s120-c-c-rp-w64-h64-mo-br100\" alt=\"charlotte leysen\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> charlotte leysen <\/div> <div class=\"ti-date\">2023-04-27<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Excellent tour and recommendations<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AGNmyxad7nV_SQ0xl755hVsbk1dKLNiIHe-P5ro97ufr=s120-c-c-rp-w64-h64-mo-ba3-br100\" alt=\"Andrea Costantino\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Andrea Costantino <\/div> <div class=\"ti-date\">2023-04-23<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Best walking tour in bordeaux!! Thanks yo Goya \ud83d\ude09<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AGNmyxZyRFTcwh2d9VvHTFp97BE_rFa6-r2f4jxyRJxA=s120-c-c-rp-w64-h64-mo-br100\" alt=\"Manuela Ruiz de Ojeda\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Manuela Ruiz de Ojeda <\/div> <div class=\"ti-date\">2023-04-23<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Muy amable Any un gran Guia y nos ha contado la historia de Burdeos de manera muy divertida y amena.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AGNmyxbXfkErjdd2j0pr5lu5Wjua5uZTOj6QdIfq0ACe=s120-c-c-rp-w64-h64-mo-br100\" alt=\"loli bouzas\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> loli bouzas <\/div> <div class=\"ti-date\">2023-04-22<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Luc\u00eda, la gallega, maravillosa. Muy amable, amena, d\u00e1ndonos much\u00edsima informaci\u00f3n de manera clara y detallada. Encantadora.\u00a1Super recomendable!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div> <div class=\"ti-footer-filter-text\">Showing only 5 star reviews<\/div> <\/div> <\/div> <\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aae8ee6 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"aae8ee6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-93fd4af\" data-id=\"93fd4af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-833adfc elementor-widget elementor-widget-gva-heading-block\" data-id=\"833adfc\" data-element_type=\"widget\" data-widget_type=\"gva-heading-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"gva-element-gva-heading-block gva-element\">   <div class=\"align-left style-1 widget gsc-heading box-align-left auto-responsive\">\r\n      <div class=\"content-inner\">\r\n         \r\n                  \r\n                     <div class=\"sub-title\"><span>\u00bfTiene alguna duda?<\/span><\/div>\r\n           \r\n         \r\n                     <h2 class=\"title\">\r\n               <span>\u00a1Preg\u00fantenos!<\/span>\r\n            <\/h2>\r\n                              <div class=\"title-desc\">Consulte nuestras preguntas frecuentes o env\u00edenos un mensaje y nos pondremos en contacto con usted lo antes posible, \u00a1prometido!<\/div>\r\n         \r\n         \r\n      <\/div>\r\n   <\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0399d23 elementor-align-left app-button elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"0399d23\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/faq\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-question-circle\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">PREGUNTAS FRECUENTES<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abd42e5 elementor-align-left app-button elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"abd42e5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/contactenos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactenos<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Free tour Saint Emilion en espa\u00f1ol Rue Guadet 1 Saint-\u00c9milion 33330 Nouvelle-Aquitaine FR RESERVAR AHORA Precio Basado en propinas Duracion 1.5 horas Tipo de tour Tour de grupo Lamentablemente no hay Saint Emilion Tours hasta nuevo aviso. Lamentamos las molestias DESCRIPCI\u00d3N Descubra el pintoresco pueblo medieval de Saint Emilion en esta nueva visita gratuita. \u00bfHa [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5513,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_joinchat":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Free Tour por Saint Emilion en espa\u00f1ol - Free Tour Burdeos<\/title>\n<meta name=\"description\" content=\"Descubra el pintoresco pueblo medieval de Saint Emilion en este nuevo Free Tour con nosotros. Las mejores visitas con Free Tours Burdeos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Free Tour por Saint Emilion en espa\u00f1ol - Free Tour Burdeos\" \/>\n<meta property=\"og:description\" content=\"Descubra el pintoresco pueblo medieval de Saint Emilion en este nuevo Free Tour con nosotros. Las mejores visitas con Free Tours Burdeos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/\" \/>\n<meta property=\"og:site_name\" content=\"Free walking tours Bordeaux\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-16T10:55:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/12\/free-tour-saint-emilion-espanol.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/\",\"url\":\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/\",\"name\":\"Free Tour por Saint Emilion en espa\u00f1ol - Free Tour Burdeos\",\"isPartOf\":{\"@id\":\"https:\/\/freewalkingtoursbordeaux.com\/#website\"},\"datePublished\":\"2022-12-09T12:45:32+00:00\",\"dateModified\":\"2024-05-16T10:55:42+00:00\",\"description\":\"Descubra el pintoresco pueblo medieval de Saint Emilion en este nuevo Free Tour con nosotros. Las mejores visitas con Free Tours Burdeos\",\"breadcrumb\":{\"@id\":\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/freewalkingtoursbordeaux.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Free Tour Saint Emilion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/freewalkingtoursbordeaux.com\/#website\",\"url\":\"https:\/\/freewalkingtoursbordeaux.com\/\",\"name\":\"Free walking tours Bordeaux\",\"description\":\"The best way to discover Bordeaux is with us. Your friendly &amp; passionate guide will show you the beautiful city Bordeaux, its culture and. its history.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/freewalkingtoursbordeaux.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Free Tour por Saint Emilion en espa\u00f1ol - Free Tour Burdeos","description":"Descubra el pintoresco pueblo medieval de Saint Emilion en este nuevo Free Tour con nosotros. Las mejores visitas con Free Tours Burdeos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/","og_locale":"es_ES","og_type":"article","og_title":"Free Tour por Saint Emilion en espa\u00f1ol - Free Tour Burdeos","og_description":"Descubra el pintoresco pueblo medieval de Saint Emilion en este nuevo Free Tour con nosotros. Las mejores visitas con Free Tours Burdeos","og_url":"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/","og_site_name":"Free walking tours Bordeaux","article_modified_time":"2024-05-16T10:55:42+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/12\/free-tour-saint-emilion-espanol.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/","url":"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/","name":"Free Tour por Saint Emilion en espa\u00f1ol - Free Tour Burdeos","isPartOf":{"@id":"https:\/\/freewalkingtoursbordeaux.com\/#website"},"datePublished":"2022-12-09T12:45:32+00:00","dateModified":"2024-05-16T10:55:42+00:00","description":"Descubra el pintoresco pueblo medieval de Saint Emilion en este nuevo Free Tour con nosotros. Las mejores visitas con Free Tours Burdeos","breadcrumb":{"@id":"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/freewalkingtoursbordeaux.com\/es\/"},{"@type":"ListItem","position":2,"name":"Free Tour Saint Emilion"}]},{"@type":"WebSite","@id":"https:\/\/freewalkingtoursbordeaux.com\/#website","url":"https:\/\/freewalkingtoursbordeaux.com\/","name":"Free walking tours Bordeaux","description":"The best way to discover Bordeaux is with us. Your friendly &amp; passionate guide will show you the beautiful city Bordeaux, its culture and. its history.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/freewalkingtoursbordeaux.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/pages\/5512"}],"collection":[{"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/comments?post=5512"}],"version-history":[{"count":0,"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/pages\/5512\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/media\/5513"}],"wp:attachment":[{"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/media?parent=5512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}