{"id":6393,"date":"2023-03-02T11:23:53","date_gmt":"2023-03-02T11:23:53","guid":{"rendered":"https:\/\/freewalkingtoursbordeaux.com\/?page_id=6393"},"modified":"2024-05-16T10:57:01","modified_gmt":"2024-05-16T10:57:01","slug":"burdeos-medieval-al-moderno-free-tour","status":"publish","type":"page","link":"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/","title":{"rendered":"FREE TOUR del Burdeos Medieval al Moderno"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6393\" class=\"elementor elementor-6393\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1761a59 elementor-section-full_width elementor-section-height-default elementor-section-height-default row-top\" data-id=\"1761a59\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e33d954\" data-id=\"e33d954\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81bd05a elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"81bd05a\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/03\/burdeos-moderno-al-medieval-free-tour-600x600.jpg\" alt=\"Free tour del burdeos moderno al medieval\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/03\/blue-lion-free-tour-del-burdeos-moderno-al-medieval-600x600.jpg\" alt=\"Free tour del burdeos moderno al medieval\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/03\/darwin-burdeos-moderno-free-tour-600x600.jpg\" alt=\"Free tour del burdeos moderno al medieval\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/03\/free-tour-del-burdeos-moderno-al-medieval-600x600.jpg\" alt=\"Free tour del burdeos moderno al medieval\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/03\/saint-michael-church-free-tour-600x600.jpg\" alt=\"Free tour del burdeos moderno al medieval\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d193da6 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"d193da6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a6a67e2\" data-id=\"a6a67e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6ff897 elementor-widget elementor-widget-heading\" data-id=\"e6ff897\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Free tour: \nDel Burdeos Medieval al Moderno<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-905abc1 elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"905abc1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7dbebda\" data-id=\"7dbebda\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-446fe80 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"446fe80\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\" las la-map-signs\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Punto de Partida: Frente a la Puerta Grosse Cloche<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\" las la-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">C\u00f3mo llegar: Tram A. Parada Saint Catherine<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\" las la-map-signs\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Final del Tour: Ecosystem Darwin<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d267fa6\" data-id=\"d267fa6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-385a8f1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"385a8f1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#book\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AHORA<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c87c142 disable-responsive\" data-id=\"c87c142\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dcd457 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"7dcd457\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-euro-sign\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tPrecio\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tFREE\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2c85773 disable-responsive\" data-id=\"2c85773\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-293628f elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"293628f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tDuraci\u00f3n\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t2 horas\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-72e892e disable-responsive\" data-id=\"72e892e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c034433 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"c034433\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-walking\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tTipo de viaje\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tGrupo\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ef3530 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"3ef3530\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e527308\" data-id=\"e527308\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d4bd20 elementor-widget elementor-widget-heading\" data-id=\"2d4bd20\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RESERVE AHORA ESTE FREE TOUR POR EL BURDEOS MEDIEVAL Y EL BURDEOS MODERNO\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1874a3f elementor-widget elementor-widget-shortcode\" data-id=\"1874a3f\" data-element_type=\"widget\" id=\"book\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><script type=\"text\/javascript\" src=\"https:\/\/widgets.bokun.io\/assets\/javascripts\/apps\/build\/BokunWidgetsLoader.js?bookingChannelUUID=62f584dc-20bc-407f-b8bf-375c586243ce\" async><\/script>\n\t \n\t<div class=\"bokunWidget\" data-src=\"https:\/\/widgets.bokun.io\/online-sales\/62f584dc-20bc-407f-b8bf-375c586243ce\/experience-calendar\/748898\"><\/div>\n\t<noscript>Please enable javascript in your browser to book<\/noscript>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43fb43f elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"43fb43f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6fddc34\" data-id=\"6fddc34\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a498f3 elementor-widget elementor-widget-text-editor\" data-id=\"2a498f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h2>Descripci\u00f3n: Free tour &#8220;Burdeos Medieval y Moderno&#8221;<\/h2><p><strong>Prep\u00e1rese para disfrutar de dos horas descubriendo el Burdeos medieval y el Burdeos moderno. Con nuestro recorrido a pie gratuito podr\u00e1 apreciar en detalle la perfecta combinaci\u00f3n de ambos mundos que supone la ciudad.<\/strong><\/p><p>Este <em>Free Tour<\/em> va m\u00e1s all\u00e1 del tour cl\u00e1sico por el centro de la ciudad.<\/p><p>\u00a1Le sorprender\u00e1 saber c\u00f3mo ha evolucionado Burdeos a lo largo de 1000 a\u00f1os y c\u00f3mo sigue sorprendi\u00e9ndonos!<\/p><p>Escuche las historias de los tiempos oscuros de la Edad Media, la creaci\u00f3n de las religiones, los castigos despiadados, el estilo de vida medieval y algunos de los tratamientos m\u00e1s extra\u00f1os de los m\u00e9dicos de la \u00e9poca.<\/p><p>Descubra la modernizaci\u00f3n de los altos edificios bordeleses, el museo moderno y el jard\u00edn bot\u00e1nico de Burdeos, entre otros muchos lugares de inter\u00e9s.<\/p><p>Nuestros gu\u00edas locales le acompa\u00f1ar\u00e1n a descubrir el lado medieval y moderno de Burdeos<\/p><ol><li>Comenzaremos el tour en el antiguo Barrio de Saint Michel : aprenda el secreto de la bas\u00edlica Saint Michel, la fundaci\u00f3n de la religi\u00f3n, el estilo de vida medieval y los tratamientos m\u00e9dicos incultos.<\/li><li>Cruzaremos de la orilla derecha a la izquierda del r\u00edo Garona y descubriremos la Bastide de nueva construcci\u00f3n<\/li><li>Conoceremos a la estrategia de Modernizaci\u00f3n de Burdeos, el famoso Ecosistema Darwin, sus modernos museos y edificios, el nuevo jard\u00edn bot\u00e1nico y muchos m\u00e1s lugares de inter\u00e9s.<\/li><\/ol><p>Todo ello, s\u00f3lo en este Tour de Burdeos Medieval y Moderno<\/p><p>\u00a1\u00danase a nuestro tour gratuito y disfrute de Burdeos de una forma ins\u00f3lita!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-533ed84 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"533ed84\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b34f88\" data-id=\"5b34f88\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2161229 elementor-widget elementor-widget-text-editor\" data-id=\"2161229\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 dir=\"ltr\">Descubra los tours de Burdeos mejor valorados:\u00a0<\/h3>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08533b0 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"08533b0\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-privado-por-burdeos\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tour privado por Burdeos\u00a0 a pie \u00ablo mejor de burdeos\u00bb: Descubre lo mejor de Burdeos con un Tour privado dise\u00f1ado personalmente.<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-cata-de-vino-burdeos\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tour de vinos: cata de vinos por Burdeos y quesos: 3 vinos + degustaci\u00f3n de quesos en un tour a pie por Chartrons.<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Free tour por Burdeos : Del Burdeos Medieval al Moderno<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-privado-del-vino-por-burdeos\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tour Grupal: Degustaci\u00f3n a ciegas de vinos y quesos de Burdeos (3 vinos y 3 quesos).<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Free tour por Saint Emilion: INDISPENSABLE!<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0426cf2 elementor-section-full_width elementor-section-height-default elementor-section-height-default row-top\" data-id=\"0426cf2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee19334\" data-id=\"ee19334\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed2d740 elementor-widget elementor-widget-gva-heading-block\" data-id=\"ed2d740\" data-element_type=\"widget\" data-widget_type=\"gva-heading-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"gva-element-gva-heading-block gva-element\">   <div class=\"align-center style-1 widget gsc-heading box-align-left auto-responsive\">\r\n      <div class=\"content-inner\">\r\n         \r\n                  \r\n                     <div class=\"sub-title\"><span>Experiencias similares<\/span><\/div>\r\n           \r\n         \r\n                     <h2 class=\"title\">\r\n               <span>Otros tours<\/span>\r\n            <\/h2>\r\n                  \r\n         \r\n      <\/div>\r\n   <\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a560e9e elementor-widget elementor-widget-global elementor-global-9785 elementor-widget-gva-services-group\" data-id=\"a560e9e\" data-element_type=\"widget\" data-widget_type=\"gva-services-group.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"gva-element-gva-services-group gva-element\">\r\n<div class=\"swiper-slider-wrapper gsc-services-group layout-carousel no-gutter style-1 \">\r\n   <div class=\"swiper-content-inner\">   \r\n      <div class=\"init-carousel-swiper swiper\" data-carousel=\"{&quot;items&quot;:4,&quot;items_lg&quot;:4,&quot;items_md&quot;:3,&quot;items_sm&quot;:2,&quot;items_xs&quot;:1,&quot;items_xx&quot;:1,&quot;effect&quot;:&quot;slide&quot;,&quot;space_between&quot;:30,&quot;loop&quot;:1,&quot;speed&quot;:600,&quot;autoplay&quot;:0,&quot;autoplay_delay&quot;:4500,&quot;autoplay_hover&quot;:1,&quot;navigation&quot;:1,&quot;pagination&quot;:0,&quot;dynamic_bullets&quot;:0,&quot;pagination_type&quot;:&quot;bullets&quot;}\">\r\n         <div class=\"swiper-wrapper\">\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Free Tour por Burdeos<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/free-tour-burdeos-1.jpg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-burdeos\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-burdeos\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Grupo peque\u00f1o: Tour con cata de vinos y quesos por Burdeos<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/Chartrons-Wine-and-cheese-scaled-1.jpg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-cata-de-vino-burdeos\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-cata-de-vino-burdeos\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Free Tour del Burdeos moderno al medieval<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/FREE-WALKING-TOUR-BORDEAUX-MEDIEVAL-TO-MODERN-scaled-1.jpg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Free Tour por Saint Emilion<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/Saint-Emilion-Wine-tour-580x450-1.jpeg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-saint-emilion\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Grupo peque\u00f1o: Tour gastron\u00f3mico de Burdeos<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/basilica-san-miguel-burdeos.jpg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-gastronomico-burdeos\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-gastronomico-burdeos\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Tour privado: Lo mejor de Burdeos<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/Bordeaux-wine-tour.jpeg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-privado-por-burdeos\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-privado-por-burdeos\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Tour privado: Lo mejor de Saint Emilion<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/05\/Village-Saint-Emilion.jpg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-saint-emilion-vino\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-saint-emilion-vino\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                           <div class=\"swiper-slide\">\r\n                  \r\n   <div class=\"service-item style-1\">\r\n      <div class=\"service-item-content\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"title\"><span>Tour: lo mejor de Burdeos a pie + degustaci\u00f3n de vinos y quesos<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"desc\"><img decoding=\"async\" src=\"http:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2024\/05\/Bordeaux-Letter.jpg\" >\n<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"read-more\">\r\n\t\t\t\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/cata-de-vino-y-quesos-en-burdeos\/\" class=\"btn-inline\">\r\n\t\t\t Read more\t\t  <\/a>\r\n\t\t  \t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t<div class=\"service-box-background\"><\/div>\r\n\t\t\t\t  <a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/cata-de-vino-y-quesos-en-burdeos\/\" class=\"link-overlay\"><\/a>\r\n\t\t  \t<\/div>\t\t\r\n\t\r\n\r\n<!-- Style II -->\r\n\t               <\/div>\r\n                     <\/div> \r\n      <\/div>\r\n   <\/div>   \r\n   <div class=\"swiper-pagination\"><\/div>   <div class=\"swiper-nav-next\"><\/div><div class=\"swiper-nav-prev\"><\/div><\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d684ffc elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"d684ffc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7466a23\" data-id=\"7466a23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fdc3aa2 elementor-widget elementor-widget-heading\" data-id=\"fdc3aa2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LO QUE OPINAN NUESTROS CLIENTES<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0e22e56 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"0e22e56\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a928910\" data-id=\"a928910\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a23b1f9 elementor-widget elementor-widget-video\" data-id=\"a23b1f9\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=CBo1il1A9FE&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;right:0;bottom:0;left:0;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%;aspect-ratio:var(--video-aspect-ratio);-o-object-fit:cover;object-fit:cover;-o-object-position:center center;object-position:center center}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-custom-embed-image-overlay{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-custom-embed-image-overlay img{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-04887d4\" data-id=\"04887d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44c348f elementor-widget elementor-widget-text-editor\" data-id=\"44c348f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\">Detalles sobre este Free Tour<\/h2><p>This tour is conducted in SPANISH, for ENGLISH, click\u00a0<a href=\"https:\/\/freewalkingtoursbordeaux.com\/free-tour-modern-to-medieval-bordeaux\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/freewalkingtoursbordeaux.com\/es\/free-tour-burdeos\/&amp;source=gmail&amp;ust=1677828937744000&amp;usg=AOvVaw1aJi2pTppZamrz62MdNkJ5\">here<\/a>.<\/p><ul><li>Este es un tour gratuito: Usted decide el donativo que dar\u00e1 al gu\u00eda por esta experiencia. Una propina media para este tour es de 12 &#8211; 15 euros por persona.<\/li><li>Nuestro Free Tour est\u00e1 dise\u00f1ado para personas en solitario y grupos peque\u00f1os. No podemos aceptar grupos de m\u00e1s de 6 personas (tampoco con reservas separadas). Esta es una pol\u00edtica de la empresa con el fin de proporcionar una excelente experiencia a todos nuestros clientes. Si su grupo es m\u00e1s numeroso, p\u00f3ngase en contacto con nosotros o reserve directamente nuestro\u00a0<a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-privado-por-burdeos\/\">Tour Privado: Lo Mejor de Burdeos Tour a Pie.<\/a><\/li><li>Este es el tour m\u00e1s ecol\u00f3gico de Burdeos. Utilizamos paraguas reciclados, Ipads reciclados y trabajamos con bares de vinos org\u00e1nicos y Ch\u00e2teaux.<\/li><li>Si hay menos de 4 reservas tendremos que cancelar el tour &#8211; \u00a1lo sentimos!<\/li><li>Si no puede reservar una fecha u hora espec\u00edfica (probablemente porque no hay m\u00e1s plazas disponibles), por favor escr\u00edbanos un mensaje o tome nuestro<a href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/tour-privado-por-burdeos\/\">\u00a0Tour Privado: Lo Mejor de Burdeos.<\/a><\/li><li style=\"list-style-type: none;\">\u00a0<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b8c21f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9b8c21f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#book\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR TU TOUR AHORA<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e397f2a elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"e397f2a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5474b4b\" data-id=\"5474b4b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2163f92 elementor-widget elementor-widget-heading\" data-id=\"2163f92\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">INCLUIDO \/ NO INCLUIDO\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-456ae86 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"456ae86\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9fe253f\" data-id=\"9fe253f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4280e7 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e4280e7\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gu\u00eda amigable y experimentado<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Una experiencia de free tour \u00fanica basada en propinas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Grandes historias y peque\u00f1os secretos de Burdeos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nuestras recomendaciones autoevaluadas para comer, beber y disfrutar la ciudad<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Un agradable paseo por el centro hist\u00f3rico de la ciudad de Burdeos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sus mascotas est\u00e1n permitidos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Con lluvia, nieve o sol - porque no hay mal tiempo cuando est\u00e1s con el mejor equipo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Este tour es apto para sillas de ruedas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-71eb9c1\" data-id=\"71eb9c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9d9aaf elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e9d9aaf\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Entrada a cualquier monumento (el itinerario no incluir\u00e1 visitas al interior de los monumentos).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Grupos de m\u00e1s de 6 personas por reserva<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24829b bg-row-theme elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"24829b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-663a9f23\" data-id=\"663a9f23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c5ae133 elementor-widget elementor-widget-gva-heading-block\" data-id=\"6c5ae133\" data-element_type=\"widget\" data-widget_type=\"gva-heading-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"gva-element-gva-heading-block gva-element\">   <div class=\"align-left style-1 widget gsc-heading box-align-left auto-responsive\">\r\n      <div class=\"content-inner\">\r\n         \r\n                  \r\n                     <div class=\"sub-title\"><span>Planifique su viaje con nosotros<\/span><\/div>\r\n           \r\n         \r\n                     <h2 class=\"title\">\r\n               <span>\u00bfPreparado para un FREE Tour inolvidable por el Burdeos medieval y el Burdeos moderno?<\/span>\r\n            <\/h2>\r\n                  \r\n         \r\n      <\/div>\r\n   <\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2f34f947\" data-id=\"2f34f947\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7029da7e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7029da7e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#book\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AHORA<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3110638 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"3110638\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40a99c7\" data-id=\"40a99c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f73c744 elementor-widget elementor-widget-heading\" data-id=\"f73c744\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Principales monumentos que visitaremos<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02417d1 elementor-widget elementor-widget-accordion\" data-id=\"02417d1\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-accordion{text-align:left}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2361\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2361\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Puerta  \u201cGrosse cloche\u201d<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2361\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2361\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2362\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2362\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Plaza Fernand Lafargue<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2362\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2362\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2363\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2363\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Bas\u00edlica Saint Michel y torre del reloj \"La fleche\"<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2363\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2363\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2364\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2364\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Pont de pierre<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2364\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2364\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2365\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2365\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Plaza de Stalingrado<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2365\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2365\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2366\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2366\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ecosistema Darwin<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2366\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2366\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2367\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2367\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Jard\u00edn Bot\u00e1nico<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2367\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2367\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8b3f89 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"b8b3f89\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-200e689\" data-id=\"200e689\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3459b6 elementor-widget elementor-widget-heading\" data-id=\"a3459b6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Con nuestro Free tour Burdeos Medieval y Moderno...<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16e4915 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"16e4915\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Visitar\u00e1 los monumentos medievales m\u00e1s importantes de Burdeos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Escuchar\u00e1 las an\u00e9cdotas y la historia de la Edad Media en la ciudad<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Descubrir\u00e1 la nueva zona de la Bastide<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ver\u00e1 el arte callejero m\u00e1s sorprendente de Burdeos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ver\u00e1 la f\u00e1brica de Picon (licor con sabor a naranja)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Terminar\u00e1 el recorrido con una hermosa puesta de sol contemplando Burdeos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Visitar\u00e1 los lugares m\u00e1s ins\u00f3litos pero m\u00e1s interesantes de Burdeos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Conocer\u00e1 a un gu\u00eda amable y experimentado que le indicar\u00e1 los mejores caf\u00e9s y vinos de la zona<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-95ce55b elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"95ce55b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0b04b1e\" data-id=\"0b04b1e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc0aa89 elementor-widget elementor-widget-heading\" data-id=\"cc0aa89\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PUNTO DE ENCUENTRO : Frente a la Puerta Grosse Cloche (53 Rue Saint James, Bordeaux)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-994a707 elementor-widget elementor-widget-google_maps\" data-id=\"994a707\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-google_maps .elementor-widget-container{overflow:hidden}.elementor-widget-google_maps .elementor-custom-embed{line-height:0}.elementor-widget-google_maps iframe{height:300px}<\/style>\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=53%20Rue%20Saint%20James%2C%20Bordeaux&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"53 Rue Saint James, Bordeaux\"\n\t\t\t\t\taria-label=\"53 Rue Saint James, Bordeaux\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f9ede0 elementor-widget elementor-widget-image\" data-id=\"2f9ede0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 05-02-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"707\" height=\"68\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/01\/IDENTIFICA-A-NUESTROS-GUI\u0301AS-CON-EL-PARAGUAS-TURQUESAAZUL..png\" class=\"attachment-large size-large wp-image-5775\" alt=\"Identifica a nuestros gu\u00edas con el paraguas azul turquesa\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0006057 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"0006057\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay_speed&quot;:1000,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/12\/BEST-COMMENTS-1.png\" alt=\"Best Comments\" \/><figcaption class=\"elementor-image-carousel-caption\">MEJORES NOTAS<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/12\/recycle-umbrella.png\" alt=\"Umbrella Recycle\" \/><figcaption class=\"elementor-image-carousel-caption\">PARAGUAS ECO<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/12\/Recycleipads.png\" alt=\"Ipad Recycle\" \/><figcaption class=\"elementor-image-carousel-caption\">IPAD REUTILIZADOS<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d13b9b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"2d13b9b9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12fcf9a2\" data-id=\"12fcf9a2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1af13ba7 elementor-widget elementor-widget-gva-heading-block\" data-id=\"1af13ba7\" data-element_type=\"widget\" data-widget_type=\"gva-heading-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"gva-element-gva-heading-block gva-element\">   <div class=\"align-center style-1 widget gsc-heading box-align-left auto-responsive\">\r\n      <div class=\"content-inner\">\r\n         \r\n                  \r\n                     <div class=\"sub-title\"><span>Testimonios y Rese\u00f1as<\/span><\/div>\r\n           \r\n         \r\n                     <h2 class=\"title\">\r\n               <span>A ellos les encantan nuestros tours<\/span>\r\n            <\/h2>\r\n                  \r\n         \r\n      <\/div>\r\n   <\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9cedfb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"9cedfb2\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c590c7\" data-id=\"6c590c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0344fbe dot-number elementor-widget elementor-widget-gva-testimonials\" data-id=\"0344fbe\" data-element_type=\"widget\" data-widget_type=\"gva-testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"gva-element-gva-testimonials gva-element\">\t<div class=\"gva-testimonial-carousel swiper-slider-wrapper style-2 \">\r\n\t\t<div class=\"swiper-content-inner\">\r\n\t\t\t<div class=\"init-carousel-swiper swiper\" data-carousel=\"{&quot;items&quot;:3,&quot;items_lg&quot;:3,&quot;items_md&quot;:3,&quot;items_sm&quot;:2,&quot;items_xs&quot;:1,&quot;items_xx&quot;:1,&quot;effect&quot;:&quot;slide&quot;,&quot;space_between&quot;:15,&quot;loop&quot;:1,&quot;speed&quot;:600,&quot;autoplay&quot;:1,&quot;autoplay_delay&quot;:4500,&quot;autoplay_hover&quot;:1,&quot;navigation&quot;:1,&quot;pagination&quot;:0,&quot;dynamic_bullets&quot;:0,&quot;pagination_type&quot;:&quot;bullets&quot;}\">\r\n\t\t\t\t<div class=\"swiper-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item swiper-slide\">\r\n\t\t\t\t\t\t\t<div class=\"testimonial-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-image\">\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/03\/free-walking-tour-photo-4-e1657135098591.jpg\" alt=\"Miriam\" \/>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-content\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-stars\">\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-quote\">\r\n\t\t\t\t\t\t\t\t\t\tTour y gu\u00eda (Leticia) maravillosos!\nEl tour fue muy interesante y entretenido, y las dos horas que dur\u00f3 se pasaron volando. Ella fue muy maja y cercana con todos, dio muy buenas recomendaciones y datos hist\u00f3ricos, fue una gran gu\u00eda.Lo recomendamos al 100%.\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-meta\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-name\">Miriam<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-job\">Espa\u00f1a - Tripadvisor<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item swiper-slide\">\r\n\t\t\t\t\t\t\t<div class=\"testimonial-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-image\">\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/04\/Free-tour-wit-Adrian-e1657134860244.jpeg\" alt=\"Alaitzp\" \/>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-content\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-stars\">\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-quote\">\r\n\t\t\t\t\t\t\t\t\t\tMuy buen Tour. Adri\u00e1n ha sido el mejor gu\u00eda!Te cuenta la historia y curiosidades interesantes de Burdeos de una forma entretenida. Adem\u00e1s te da muchas ideas para comer, vistas, salir, diferentes.\nSuper recomendable\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-meta\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-name\">Alaitzp<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-job\">Espa\u00f1a - Tripadvisor<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item swiper-slide\">\r\n\t\t\t\t\t\t\t<div class=\"testimonial-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-image\">\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/04\/Free-Walking-Tour-Bordeaux-2-e1657134909391.jpeg\" alt=\"Tatiana\" \/>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-content\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-stars\">\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-quote\">\r\n\t\t\t\t\t\t\t\t\t\tS\u00faper recomendado!\nExcelente ! Me gust\u00f3 mucho descubrir un poco de la ciudad de esta manera. Tips muy interesante de\nla ciudad y buenos consejos para comer y probar buenos vinos !\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-meta\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-name\">Tatiana<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-job\">Espa\u00f1a - Tripadvisor<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item swiper-slide\">\r\n\t\t\t\t\t\t\t<div class=\"testimonial-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-image\">\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2021-07-21-at-14.23.06-e1657135052831.jpeg\" alt=\"Maria\" \/>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-content\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-stars\">\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-quote\">\r\n\t\t\t\t\t\t\t\t\t\tVisita con amigas a Burdeos.\nLa gu\u00eda Melanie ha sido maravillosa! Sus explicaciones fant\u00e1sticas!! Y ella es encantadora! Hemos disfrutado mucho y aprendido bastante.\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-meta\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-name\">Maria<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-job\">Espa\u00f1a - Tripadvisor<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item swiper-slide\">\r\n\t\t\t\t\t\t\t<div class=\"testimonial-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-image\">\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2022\/03\/free-walking-tour-bordeaux-image-1-e1657134980341.jpg\" alt=\"Marcher\" \/>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"testimonial-content\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-stars\">\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-star\"><\/i>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-quote\">\r\n\t\t\t\t\t\t\t\t\t\tLuc\u00eda (La Gallega) ha sido una gu\u00eda magn\u00edfica! Super simp\u00e1tica, amable y atenta a cualquier pregunta o comentario que se le hiciera. Recomendable 100%!!!\n\nEl recorrido es muy bonito, lleno de historia y perfectamente \"aguantable\" en cuanto a cansancio.\n\nPerfecto para familias, amigos, parejas, etc.\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"testimonial-meta\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-name\">Marcher<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"testimonial-job\">Espa\u00f1a - Tripadvisor<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>   \r\n\t\t\t\t\t\t\t\t\t<\/div>   \r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t\t      <div class=\"swiper-nav-next\"><\/div><div class=\"swiper-nav-prev\"><\/div>\t<\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f388a4 elementor-widget elementor-widget-shortcode\" data-id=\"4f388a4\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"ti-widget ti-goog\" data-layout-id=\"5\" data-set-id=\"ligth-border\" data-pid=\"\" data-pager-autoplay-timeout=\"6\" data-review-target-width=\"275\" data-language=\"en\" > <div class=\"ti-widget-container ti-col-4\"> <div class=\"ti-footer source-Google\"> <div class=\"ti-rating-text\"> <strong class=\"ti-rating\"> Excellent <\/strong> <\/div> <span class=\"ti-stars star-lg\"> <span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span> <\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\">Based on <strong>540 reviews<\/strong><\/span> <\/div> <div class=\"ti-large-logo\"> <div class=\"ti-v-center\"> <img decoding=\"async\" class=\"ti-logo-fb\" src=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/logo.svg\" width=\"150\" height=\"25\" alt=\"Google\" \/> <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\"><\/div> <div class=\"ti-prev\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a-\/ACB-R5QjnJ0DdCXxCs9czqu-f9BFaiV73HahOH2vmDPjng=s120-c-c-rp-w64-h64-mo-br100\" alt=\"teresa arozena\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> teresa arozena <\/div> <div class=\"ti-date\">2023-04-28<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Muy buena experiencia, muy recomendable... todo el desarrollo hist\u00f3rico de Burdeos de una manera din\u00e1mica y ligera. Una buena forma de iniciaci\u00f3n en la ciudad con mucha informaci\u00f3n \u00fatil.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AGNmyxZsbiFZgxS7Pb4X71fI05SAHJPDXM7bld2o0wLF=s120-c-c-rp-w64-h64-mo-br100\" alt=\"Belen Garc\u00eda Balado\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Belen Garc\u00eda Balado <\/div> <div class=\"ti-date\">2023-04-28<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Luc\u00eda espectacular su explicaci\u00f3n y cercan\u00eda<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AGNmyxaryhpqPSQCYv6lsu0jjmYBMKzw77pSPVK3A4d9=s120-c-c-rp-w64-h64-mo-ba3-br100\" alt=\"Christine W\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Christine W <\/div> <div class=\"ti-date\">2023-04-27<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Lucia was our tour guide and she was amazing, extremely knowledgable and gave us an awesome tour. She gave us lots of recommendations for restaurants and other sites to see while in Bordeaux. Highly recommend this tour!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a-\/ACB-R5SFc8TmQKf6yZmyKTCJA7HN34YCJz0zDGSBh-OH=s120-c-c-rp-w64-h64-mo-ba3-br100\" alt=\"\u0414\u0430\u0440\u0438\u043d\u0430 \u0418\u0432\u0430\u043d\u0447\u0435\u043d\u043a\u043e\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> \u0414\u0430\u0440\u0438\u043d\u0430 \u0418\u0432\u0430\u043d\u0447\u0435\u043d\u043a\u043e <\/div> <div class=\"ti-date\">2023-04-27<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->The tour was really interesting, even back home I decided to read more about Ali\u00e9nor d'Aquitaine. Thank you!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AGNmyxY-naQKfVKjLZvBhIcAtCHJ7BMbkVShGV3tg8-h=s120-c-c-rp-w64-h64-mo-br100\" alt=\"charlotte leysen\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> charlotte leysen <\/div> <div class=\"ti-date\">2023-04-27<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Excellent tour and recommendations<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AGNmyxad7nV_SQ0xl755hVsbk1dKLNiIHe-P5ro97ufr=s120-c-c-rp-w64-h64-mo-ba3-br100\" alt=\"Andrea Costantino\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Andrea Costantino <\/div> <div class=\"ti-date\">2023-04-23<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Best walking tour in bordeaux!! Thanks yo Goya \ud83d\ude09<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AGNmyxZyRFTcwh2d9VvHTFp97BE_rFa6-r2f4jxyRJxA=s120-c-c-rp-w64-h64-mo-br100\" alt=\"Manuela Ruiz de Ojeda\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Manuela Ruiz de Ojeda <\/div> <div class=\"ti-date\">2023-04-23<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Muy amable Any un gran Guia y nos ha contado la historia de Burdeos de manera muy divertida y amena.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google\" > <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-profile-img\"> <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AGNmyxbXfkErjdd2j0pr5lu5Wjua5uZTOj6QdIfq0ACe=s120-c-c-rp-w64-h64-mo-br100\" alt=\"loli bouzas\" \/> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> loli bouzas <\/div> <div class=\"ti-date\">2023-04-22<\/div> <\/div> <\/div> <span class=\"ti-stars\"><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><span class=\"ti-star f\"><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Luc\u00eda, la gallega, maravillosa. Muy amable, amena, d\u00e1ndonos much\u00edsima informaci\u00f3n de manera clara y detallada. Encantadora.\u00a1Super recomendable!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Hide\" data-open-text=\"Read more\" ><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div> <div class=\"ti-footer-filter-text\">Showing only 5 star reviews<\/div> <\/div> <\/div> <\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37af9af elementor-widget elementor-widget-gva-heading-block\" data-id=\"37af9af\" data-element_type=\"widget\" data-widget_type=\"gva-heading-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"gva-element-gva-heading-block gva-element\">   <div class=\"align-left style-1 widget gsc-heading box-align-left auto-responsive\">\r\n      <div class=\"content-inner\">\r\n         \r\n                  \r\n                     <div class=\"sub-title\"><span>\u00bfTiene alguna duda?<\/span><\/div>\r\n           \r\n         \r\n                     <h2 class=\"title\">\r\n               <span>\u00a1Preg\u00fantenos!<\/span>\r\n            <\/h2>\r\n                              <div class=\"title-desc\">Consulte nuestras preguntas frecuentes o env\u00edenos un mensaje y nos pondremos en contacto con usted lo antes posible, \u00a1prometido!<\/div>\r\n         \r\n         \r\n      <\/div>\r\n   <\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c8d64e elementor-align-left app-button elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"0c8d64e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/faq\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-question-circle\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">PREGUNTAS FRECUENTES<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b955e90 elementor-align-left app-button elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"b955e90\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/contactenos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactenos<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Free tour: Del Burdeos Medieval al Moderno Punto de Partida: Frente a la Puerta Grosse Cloche C\u00f3mo llegar: Tram A. Parada Saint Catherine Final del Tour: Ecosystem Darwin RESERVAR AHORA Precio FREE Duraci\u00f3n 2 horas Tipo de viaje Grupo RESERVE AHORA ESTE FREE TOUR POR EL BURDEOS MEDIEVAL Y EL BURDEOS MODERNO Please enable javascript [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6395,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_joinchat":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FREE TOUR del Burdeos Medieval al Moderno - Free walking tours Bordeaux<\/title>\n<meta name=\"description\" content=\"En este Free Tour descubrir\u00e1s c\u00f3mo ha cambiado Burdeos desde el medievo hasta hoy. \u00a1Conoce todas las historias y an\u00e9cdotas con nuestros gu\u00edas!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FREE TOUR del Burdeos Medieval al Moderno - Free walking tours Bordeaux\" \/>\n<meta property=\"og:description\" content=\"En este Free Tour descubrir\u00e1s c\u00f3mo ha cambiado Burdeos desde el medievo hasta hoy. \u00a1Conoce todas las historias y an\u00e9cdotas con nuestros gu\u00edas!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/\" \/>\n<meta property=\"og:site_name\" content=\"Free walking tours Bordeaux\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-16T10:57:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/03\/burdeos-medieval-y-moderno-free-tour.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/\",\"url\":\"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/\",\"name\":\"FREE TOUR del Burdeos Medieval al Moderno - Free walking tours Bordeaux\",\"isPartOf\":{\"@id\":\"https:\/\/freewalkingtoursbordeaux.com\/#website\"},\"datePublished\":\"2023-03-02T11:23:53+00:00\",\"dateModified\":\"2024-05-16T10:57:01+00:00\",\"description\":\"En este Free Tour descubrir\u00e1s c\u00f3mo ha cambiado Burdeos desde el medievo hasta hoy. \u00a1Conoce todas las historias y an\u00e9cdotas con nuestros gu\u00edas!\",\"breadcrumb\":{\"@id\":\"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/freewalkingtoursbordeaux.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FREE TOUR del Burdeos Medieval al Moderno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/freewalkingtoursbordeaux.com\/#website\",\"url\":\"https:\/\/freewalkingtoursbordeaux.com\/\",\"name\":\"Free walking tours Bordeaux\",\"description\":\"The best way to discover Bordeaux is with us. Your friendly &amp; passionate guide will show you the beautiful city Bordeaux, its culture and. its history.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/freewalkingtoursbordeaux.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FREE TOUR del Burdeos Medieval al Moderno - Free walking tours Bordeaux","description":"En este Free Tour descubrir\u00e1s c\u00f3mo ha cambiado Burdeos desde el medievo hasta hoy. \u00a1Conoce todas las historias y an\u00e9cdotas con nuestros gu\u00edas!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/","og_locale":"es_ES","og_type":"article","og_title":"FREE TOUR del Burdeos Medieval al Moderno - Free walking tours Bordeaux","og_description":"En este Free Tour descubrir\u00e1s c\u00f3mo ha cambiado Burdeos desde el medievo hasta hoy. \u00a1Conoce todas las historias y an\u00e9cdotas con nuestros gu\u00edas!","og_url":"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/","og_site_name":"Free walking tours Bordeaux","article_modified_time":"2024-05-16T10:57:01+00:00","og_image":[{"width":1000,"height":1000,"url":"http:\/\/freewalkingtoursbordeaux.com\/wp-content\/uploads\/2023\/03\/burdeos-medieval-y-moderno-free-tour.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/","url":"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/","name":"FREE TOUR del Burdeos Medieval al Moderno - Free walking tours Bordeaux","isPartOf":{"@id":"https:\/\/freewalkingtoursbordeaux.com\/#website"},"datePublished":"2023-03-02T11:23:53+00:00","dateModified":"2024-05-16T10:57:01+00:00","description":"En este Free Tour descubrir\u00e1s c\u00f3mo ha cambiado Burdeos desde el medievo hasta hoy. \u00a1Conoce todas las historias y an\u00e9cdotas con nuestros gu\u00edas!","breadcrumb":{"@id":"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/freewalkingtoursbordeaux.com\/es\/burdeos-medieval-al-moderno-free-tour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/freewalkingtoursbordeaux.com\/es\/"},{"@type":"ListItem","position":2,"name":"FREE TOUR del Burdeos Medieval al Moderno"}]},{"@type":"WebSite","@id":"https:\/\/freewalkingtoursbordeaux.com\/#website","url":"https:\/\/freewalkingtoursbordeaux.com\/","name":"Free walking tours Bordeaux","description":"The best way to discover Bordeaux is with us. Your friendly &amp; passionate guide will show you the beautiful city Bordeaux, its culture and. its history.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/freewalkingtoursbordeaux.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/pages\/6393"}],"collection":[{"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/comments?post=6393"}],"version-history":[{"count":0,"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/pages\/6393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/media\/6395"}],"wp:attachment":[{"href":"https:\/\/freewalkingtoursbordeaux.com\/es\/wp-json\/wp\/v2\/media?parent=6393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}